{"id":6343,"date":"2010-03-30T07:09:18","date_gmt":"2010-03-30T07:09:18","guid":{"rendered":"http:\/\/www.ipsnoticias.net\/portuguese\/?p=6343"},"modified":"2010-03-30T07:09:18","modified_gmt":"2010-03-30T07:09:18","slug":"politica-ruanda-mulher-concorre-a-importante-cargo","status":"publish","type":"post","link":"https:\/\/www.ipsnews.net\/portuguese\/2010\/03\/africa\/politica-ruanda-mulher-concorre-a-importante-cargo\/","title":{"rendered":"POL\u00cdTICA-RUANDA: Mulher Concorre a Importante Cargo"},"content":{"rendered":"<p>KIGALI, 30\/03\/2010 &ndash; Em m\u00e9dia, as mulheres constituem 18.8 por cento dos representantes nos parlamentos em todo o mundo, de acordo com a Uni\u00e3o Inter-Parlamentar (UIP). Este desequil\u00edbrio entre os sexos tem sido sujeito a muitas cr\u00edticas feministas, e t\u00eam-se organizado muitas campanhas a favor da sua altera\u00e7\u00e3o. Contudo, a situa\u00e7\u00e3o \u00e9 diferente no Ruanda. <!--more--> Com uma representa\u00e7\u00e3o de 56 por cento, as mulheres ruandesas est\u00e3o no topo das classifica\u00e7\u00f5es mundiais referentes \u00e0 presen\u00e7a das mulheres nos parlamentos nacionais, apesar do genoc\u00eddio de 1994 que deixou mais de 800.000 pessoas mortas e incont\u00e1veis mulheres violadas. <\/p>\n<p>As mulheres ruandesas atingiram este n\u00famero impressionante no parlamento ao desempenharem um papel activo na reconstru\u00e7\u00e3o do pa\u00eds e ao promoverem intensamente a cria\u00e7\u00e3o de uma quota constitucional para as mulheres na c\u00e2mara baixa do parlamento. Tamb\u00e9m conseguiram promover a cria\u00e7\u00e3o de um Minist\u00e9rio governamental para quest\u00f5es femininas para defender pol\u00edticas que beneficiem os interesses das mulheres. <\/p>\n<p>N\u00e3o foi surpresa nenhuma quando Victoire Ingabire regressou a casa em Janeiro de 2010, depois de ter passado 16 anos no ex\u00edlio na Holanda, e imediatamente declarou que estava interessada no cargo pol\u00edtico mais importante no seu pa\u00eds.<\/p>\n<p>\u201cO meu objectivo \u00e9 introduzir o estado de direito no Ruanda e criar um estado constitucional onde os padr\u00f5es democr\u00e1ticos internacionais sejam respeitados e onde o nacionalismo seja, finalmente, o alicerce de todas as institui\u00e7\u00f5es p\u00fablicas,\u201d disse \u00e0 IPS. <\/p>\n<p>Ingabire, de etnia hutu, nasceu no dia 3 de Outubro de 1968 em Kibilira, no Ruanda ocidental. \u00c9 Presidente das For\u00e7as Democr\u00e1ticas Unificadas (UDF), uma coliga\u00e7\u00e3o de partidos da oposi\u00e7\u00e3o ruandeses com membros no Ruanda, Estados Unidos da Am\u00e9rica e Canad\u00e1. Foi eleita pelo partido como candidata oficial para as pr\u00f3ximas elei\u00e7oes presidenciais ruandesas em Agosto de 2010.<\/p>\n<p>Dada a recente hist\u00f3ria do Ruanda, colocar uma mulher no cargo mais elevado do pa\u00eds pode n\u00e3o parecer muito estranho para os eleitores ruandeses. As mulheres n\u00e3o s\u00f3 controlam o parlamento, mas diversas mulheres chefiam minist\u00e9rios importantes no actual governo. O pa\u00eds j\u00e1 tinha tido, no passado, uma mulher como Primeiro-Ministro. Agathe Uwilingiyimana dirigiu o governo de transi\u00e7\u00e3o durante quase um ano antes do seu assassinato em Abril de 1994. <\/p>\n<p>No entanto, Ingabire pensa que, apesar dos n\u00fameros, as mulheres do seu pa\u00eds ainda est\u00e3o longe de conseguirem fazer alguma diferen\u00e7a em termos pol\u00edticos. <\/p>\n<p>\u201cN\u00e3o existe autonomiza\u00e7\u00e3o das mulheres. \u00c9 tudo fic\u00e7\u00e3o. O que importa n\u00e3o \u00e9 o n\u00famero mas a partilha de poder que lhes \u00e9 concedido. Ainda h\u00e1 um longo caminho a percorrer para traduzir o peso nominal das mulheres numa partilha eficaz do poder de decis\u00e3o,\u201d disse Ingabire. <\/p>\n<p>Esta \u00e9 uma das raz\u00f5es que a convenceu a participar nas elei\u00e7\u00f5es. \u201cAinda est\u00e1 por se descobrir o peso pol\u00edtico das mulheres. N\u00e3o estou interessada em mudan\u00e7as cosm\u00e9ticas, onde as mulheres s\u00e3o propostas por motivos propagand\u00edsticos. Quero ver as impress\u00f5es digitais das mulheres em todos os sectores da sociedade,\u201d declarou \u00e0 IPS. \u201cA minha candidatura n\u00e3o deve ser um instrumento assente nas mulheres mas antes uma candidatura que fa\u00e7a diferen\u00e7a.\u201d <\/p>\n<p>Figura controversa, quando regressou do ex\u00edlio Ingabire pediu justi\u00e7a n\u00e3o s\u00f3 para os Tutsis assassinados durante o genoc\u00eddio, mas tamb\u00e9m para os Hutus que por ele foram afectados.<\/p>\n<p>Disse ainda que a intimida\u00e7\u00e3o que sentiu durante a campanha por parte de agentes da seguran\u00e7a do estado constitui um testemunho que a participa\u00e7\u00e3o feminina na pol\u00edtica do pa\u00eds n\u00e3o \u00e9 um fen\u00f3meno aceite naturalmente.<\/p>\n<p>Yaliwe Clarke, professora do Instituto Africano do G\u00e9nero, tamb\u00e9m fez uma advert\u00eancia sobre a necessidade de se olhar para al\u00e9m dos n\u00fameros. \u201cJ\u00e1 se previu que, se houver uma massa cr\u00edtica de mulheres no poder, ent\u00e3o as coisas podem mudar.\u201d<\/p>\n<p>Contudo, acrescentou que n\u00e3o era um dado adquirido que todas as mulheres eleitas acreditam na igualdade do g\u00e9nero. \u201cPor exemplo, ser\u00e1 que elas ir\u00e3o lidar com quest\u00f5es que t\u00eam a ver com a viol\u00eancia baseada no g\u00e9nero?\u201d indagou. <\/p>\n<p>Entretanto, as mulheres de outros pa\u00edses em transi\u00e7\u00e3o procuram obter do Ruanda li\u00e7\u00f5es sobre como se deve atingir a paridade na pol\u00edtica e no processo de tomada de decis\u00f5es. Beater Nyamupinga, Presidente do Grupo Parlamentar das Mulheres do Zimbabwe, acredita que o Ruanda pode transmitir uma s\u00e9rie de li\u00e7\u00f5es \u00e0s mulheres do seu pa\u00eds sobre a forma de concretizar a igualdade do g\u00e9nero mencionada na constitui\u00e7\u00e3o. Neste momento, est\u00e1 em curso no Zimbabwe um processo de redac\u00e7\u00e3o da constitui\u00e7\u00e3o em confomridade com o Acordo Pol\u00edtico Global assinado pelos tr\u00eas principais rivais pol\u00edticos ap\u00f3s as elei\u00e7\u00f5es de 2008, marcadas pela viol\u00eancia.<\/p>\n<p>\u201cPrecisamos simplesmente de construir mecanismos que respondam \u00e0s necessidades das mulheres. As mulheres ruandesas ensinaram-nos a defender a representa\u00e7\u00e3o proporcional em todas as esferas atrav\u00e9s de sistemas eleitorais que devem garantir uma quota igual \u00e0s mulheres,\u201d afirmou Nyamupinga. <\/p>\n<p>Ingabire admite que criticar a presid\u00eancia, cargo actualmente exercido por Paul Kagame, da Frente Patri\u00f3tica Ruandesa, que tem encaminhado o pa\u00eds na rota do crescimento desde 1994, \u00e9 uma tarefa gigantesca. Mas est\u00e1 optimista. <\/p>\n<p>Entre as quest\u00f5es que tem usado para atrair eleitores est\u00e1 o seu apelo para a cria\u00e7\u00e3o de um Comit\u00e9 sobre a Verdade, Justi\u00e7a e Reconcilia\u00e7\u00e3o, para ajudar os Ruandeses a atingir a verdadeira reconcilia\u00e7\u00e3o. Tamb\u00e9m prometeu estabelecer uma comiss\u00e3o sem influ\u00eancia pol\u00edtica respons\u00e1vel por tornar a redigir e interpretar a verdadeira hist\u00f3ria do Ruanda, assim como aprovar uma lei que estabele\u00e7a o direito \u00e0 propriedade privada e \u00e0 protec\u00e7\u00e3o dos cidad\u00e3os mais pobres, e que garanta a igualdade perante a lei. <\/p>\n<p>\u201cA probabilidade de eu conquistar este cargo elevado depende da vontade do povo de criar uma nova onda de mudan\u00e7a na governa\u00e7\u00e3o em termos de transpar\u00eancia, justi\u00e7a para todos, reconcilia\u00e7\u00e3o, e boa vizinhan\u00e7a. Vou ganhar porque o povo quer mudar de uma gest\u00e3o pol\u00edtica p\u00f3s-guerra para uma democracia plena,\u201d disse Ingabire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KIGALI, 30\/03\/2010 &ndash; Em m\u00e9dia, as mulheres constituem 18.8 por cento dos representantes nos parlamentos em todo o mundo, de acordo com a Uni\u00e3o Inter-Parlamentar (UIP). Este desequil\u00edbrio entre os sexos tem sido sujeito a muitas cr\u00edticas feministas, e t\u00eam-se organizado muitas campanhas a favor da sua altera\u00e7\u00e3o. Contudo, a situa\u00e7\u00e3o \u00e9 diferente no Ruanda. <a href=\"https:\/\/www.ipsnews.net\/portuguese\/2010\/03\/africa\/politica-ruanda-mulher-concorre-a-importante-cargo\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":191,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6343","post","type-post","status-publish","format-standard","hentry","category-africa"],"_links":{"self":[{"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/posts\/6343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/comments?post=6343"}],"version-history":[{"count":0,"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/posts\/6343\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/media?parent=6343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/categories?post=6343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipsnews.net\/portuguese\/wp-json\/wp\/v2\/tags?post=6343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}